{"id":7257,"date":"2025-05-20T12:09:56","date_gmt":"2025-05-20T12:09:56","guid":{"rendered":"https:\/\/bangpremier.fr\/index.php\/2025\/05\/20\/cannes-denzel-washington-recadre-un-photographe-sur-les-marches\/"},"modified":"2025-05-20T12:09:57","modified_gmt":"2025-05-20T12:09:57","slug":"cannes-denzel-washington-recadre-un-photographe-sur-les-marches","status":"publish","type":"post","link":"https:\/\/bangpremier.fr\/index.php\/2025\/05\/20\/cannes-denzel-washington-recadre-un-photographe-sur-les-marches\/","title":{"rendered":"Cannes : Denzel Washington recadre un photographe sur les marches"},"content":{"rendered":"<p><b>2025-05-20 12:09:56<\/b><br \/>\n<BR>Denzel Washington s&#8217;est emport\u00e9 contre un photographe durant le Festival de Cannes. L&#8217;acteur foulait le tapis rouge du festival pour l&#8217;avant-premi\u00e8re de son nouveau film &#8220;Highest 2 Lowest&#8221; lundi lorsqu&#8217;il a confront\u00e9 un photographe qui semblait lui avoir tap\u00e9 sur le bras. Denzel a \u00e9t\u00e9 vu en train de le r\u00e9primander bien que le photographe continuait de rire et de sourire pendant l&#8217;\u00e9change. Le photographe a de nouveau saisi le bras de Denzel, et la star, furieuse, a repouss\u00e9 sa main. Il a alors cri\u00e9 &#8220;Arr\u00eatez, arr\u00eatez&#8221; en pointant le photographe du doigt, avant de partir en trombe.<BR><br \/>\nLa soir\u00e9e s&#8217;est toutefois am\u00e9lior\u00e9e pour Denzel puisque le r\u00e9alisateur Spike Lee l&#8217;a surpris en lui remettant une Palme d&#8217;or d&#8217;honneur.<BR><br \/>\nIl a avou\u00e9 : &#8220;C&#8217;est une surprise totale pour moi, je suis tr\u00e8s \u00e9mu. C&#8217;est une grande opportunit\u00e9 de collaborer \u00e0 nouveau avec mon fr\u00e8re, un fr\u00e8re d&#8217;une autre m\u00e8re, et d&#8217;\u00eatre \u00e0 nouveau ici \u00e0 Cannes. Nous sommes un groupe tr\u00e8s privil\u00e9gi\u00e9 dans cette salle, car nous pouvons faire des films, porter des smokings et de beaux v\u00eatements, nous habiller et \u00eatre pay\u00e9s pour cela. Nous sommes b\u00e9nis au-del\u00e0 de toute mesure. Du fond du c\u0153ur, je vous remercie tous&#8221;.<br \/>\n<br \/><a href=\"https:\/\/bangpremier.com\/\" target=\"_blank\"> Visit Bang Premier (main website) <\/a><br \/>\n<br \/><script src=\"https:\/\/geo.dailymotion.com\/player\/xt7m2.js\" data-params=\"mute=true\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2025-05-20 12:09:56 Denzel Washington s&#8217;est emport\u00e9 contre un photographe durant le Festival de Cannes. L&#8217;acteur foulait le tapis rouge du festival pour l&#8217;avant-premi\u00e8re de son nouveau film &#8220;Highest 2 Lowest&#8221;&hellip;<\/p>\n","protected":false},"author":1,"featured_media":7258,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-people"],"_links":{"self":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/7257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/comments?post=7257"}],"version-history":[{"count":1,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/7257\/revisions"}],"predecessor-version":[{"id":7259,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/7257\/revisions\/7259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/media\/7258"}],"wp:attachment":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/media?parent=7257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/categories?post=7257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/tags?post=7257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}