{"id":13291,"date":"2026-07-15T13:06:03","date_gmt":"2026-07-15T13:06:03","guid":{"rendered":"https:\/\/bangpremier.fr\/index.php\/2026\/07\/15\/george-lucas-donne-son-opinion-sur-lintelligence-artificielle\/"},"modified":"2026-07-15T13:06:05","modified_gmt":"2026-07-15T13:06:05","slug":"george-lucas-donne-son-opinion-sur-lintelligence-artificielle","status":"publish","type":"post","link":"https:\/\/bangpremier.fr\/index.php\/2026\/07\/15\/george-lucas-donne-son-opinion-sur-lintelligence-artificielle\/","title":{"rendered":"George Lucas donne son opinion sur l&#039;intelligence artificielle"},"content":{"rendered":"<p><b>2026-07-15 13:06:02<\/b><br \/>\n<BR>George Lucas pense que l\u2019intelligence artificielle ne peut pas \u00eatre \u00e9vit\u00e9. Le cr\u00e9ateur de \u201cStar Wars\u201d a insist\u00e9 sur le fait que les gens ne peuvent rien faire face \u00e0 l\u2019IA.<BR><br \/>\n \u201cL\u2019intelligence artificielle nous permet de r\u00e9aliser des films beaucoup plus facilement&#8221; a d\u00e9clar\u00e9 le cin\u00e9aste \u00e0 Rabbit&#8217;s Foot. &#8220;C\u2019est un peu comme si j\u2019\u00e9tais assis ici en disant : \u201cEh bien, je crois que l\u2019attelage \u00e0 cheval, c\u2019est vraiment ce qu\u2019il y a de mieux. Ces voitures, elles tombent en panne, elles ont besoin d\u2019essence, elles posent toutes sortes de probl\u00e8mes et, tr\u00e8s bient\u00f4t, on les transformera en chars d\u2019assaut, puis elles tueront des gens. On ne peut rien y faire. C\u2019est le progr\u00e8s, c\u2019est l\u2019avenir.\u201d<BR><br \/>\nCependant, George Lucas n\u2019appr\u00e9cie pas que Hollywood recoure \u00e0 des groupes de discussion pour savoir ce que les fans pensent d\u2019un film avant sa sortie, car il estime que le public a trop d\u2019influence de nos jours.<BR><br \/>\n\u201cJe n\u2019aime pas les groupes de discussion&#8221; a confi\u00e9 le r\u00e9alisateur. &#8220;Le public ne sait pas ce qu\u2019il veut voir. S\u2019il n\u2019aime pas un personnage, c\u2019est int\u00e9ressant, et en tant que cin\u00e9aste, je veux comprendre pourquoi. Mais quand les studios entendent \u00e7a, ils en tirent le mauvais message. Ils laissent le public faire le film \u00e0 leur place. Bien s\u00fbr, aujourd\u2019hui, ils en font des folies.\u201d<br \/>\n<br \/><a href=\"https:\/\/bangpremier.com\/\" target=\"_blank\"> Visit Bang Premier (main website) <\/a><br \/>\n<br \/><script src=\"https:\/\/geo.dailymotion.com\/player\/xt7m2.js\" data-params=\"mute=true\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2026-07-15 13:06:02 George Lucas pense que l\u2019intelligence artificielle ne peut pas \u00eatre \u00e9vit\u00e9. Le cr\u00e9ateur de \u201cStar Wars\u201d a insist\u00e9 sur le fait que les gens ne peuvent rien faire&hellip;<\/p>\n","protected":false},"author":1,"featured_media":13292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-people"],"_links":{"self":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/13291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/comments?post=13291"}],"version-history":[{"count":1,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/13291\/revisions"}],"predecessor-version":[{"id":13293,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/posts\/13291\/revisions\/13293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/media\/13292"}],"wp:attachment":[{"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/media?parent=13291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/categories?post=13291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bangpremier.fr\/index.php\/wp-json\/wp\/v2\/tags?post=13291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}